{"id":1062,"count":0,"description":"TISSUE PAPER \u2013 Thickness Determination.","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/","name":"EN 12625-3","slug":"en-12625-3","taxonomy":"en","parent":1009,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"TISSUE PAPER \u2013 Thickness Determination.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/#listItem\",\"name\":\"1-2-3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/#listItem\",\"position\":3,\"name\":\"1-2-3\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/en-12625-3\\\/#listItem\",\"name\":\"EN 12625-3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/en-12625-3\\\/#listItem\",\"position\":4,\"name\":\"EN 12625-3\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/1-2-3\\\/#listItem\",\"name\":\"1-2-3\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/#collectionpage\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/\",\"name\":\"EN 12625-3 - Techlab Systems\",\"description\":\"TISSUE PAPER \\u2013 Thickness Determination.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"telephone\":\"+34943470007\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/Techlabsystems-identidad-en.svg\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/#organizationLogo\",\"width\":677,\"height\":133},\"image\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1062\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"EN 12625-3 - Techlab Systems","description":"TISSUE PAPER \u2013 Thickness Determination.","canonical_url":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","position":1,"name":"Home","item":"https:\/\/techlabsystems.com\/eng","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/techlabsystems.com\/eng\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/#listItem","name":"1-2-3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/#listItem","position":3,"name":"1-2-3","item":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/#listItem","name":"EN 12625-3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/#listItem","position":4,"name":"EN 12625-3","previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/#listItem","name":"1-2-3"}}]},{"@type":"CollectionPage","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/#collectionpage","url":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/","name":"EN 12625-3 - Techlab Systems","description":"TISSUE PAPER \u2013 Thickness Determination.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/techlabsystems.com\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/techlabsystems.com\/eng\/#organization","name":"Techlab Systems","description":"Equipment for quality control tests","url":"https:\/\/techlabsystems.com\/eng\/","telephone":"+34943470007","logo":{"@type":"ImageObject","url":"https:\/\/techlabsystems.com\/eng\/wp-content\/uploads\/sites\/2\/2021\/04\/Techlabsystems-identidad-en.svg","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/#organizationLogo","width":677,"height":133},"image":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/techlabsystems.com\/eng\/#website","url":"https:\/\/techlabsystems.com\/eng\/","name":"Techlab Systems","description":"Equipment for quality control tests","inLanguage":"en-US","publisher":{"@id":"https:\/\/techlabsystems.com\/eng\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/products\/\" title=\"Products\">Products<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/\" title=\"1-2-3\">1-2-3<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEN 12625-3\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/techlabsystems.com\/eng"},{"label":"Products","link":"https:\/\/techlabsystems.com\/eng\/products\/"},{"label":"1-2-3","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/"},{"label":"EN 12625-3","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/1-2-3\/en-12625-3\/"}],"_links":{"self":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en"}],"about":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/taxonomies\/en"}],"up":[{"embeddable":true,"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1009"}],"wp:post_type":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/product?en=1062"},{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/normas?en=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}