{"id":1290,"count":0,"description":"PAPER AND BOARD \u2013 Thickness\/Bulk Density Determination-Individual Sheets","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/","name":"EN 534","slug":"en-534","taxonomy":"en","parent":1263,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"PAPER AND BOARD \u2013 Thickness\/Bulk Density Determination-Individual Sheets\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/#listItem\",\"name\":\"4-5-6\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/#listItem\",\"position\":3,\"name\":\"4-5-6\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/en-534\\\/#listItem\",\"name\":\"EN 534\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/en-534\\\/#listItem\",\"position\":4,\"name\":\"EN 534\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/norma-en\\\/4-5-6\\\/#listItem\",\"name\":\"4-5-6\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/#collectionpage\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/\",\"name\":\"EN 534 - Techlab Systems\",\"description\":\"PAPER AND BOARD \\u2013 Thickness\\\/Bulk Density Determination-Individual Sheets\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"telephone\":\"+34943470007\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/Techlabsystems-identidad-en.svg\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/#organizationLogo\",\"width\":677,\"height\":133},\"image\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/en\\\/1290\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"EN 534 - Techlab Systems","description":"PAPER AND BOARD \u2013 Thickness\/Bulk Density Determination-Individual Sheets","canonical_url":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","position":1,"name":"Home","item":"https:\/\/techlabsystems.com\/eng","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/techlabsystems.com\/eng\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/#listItem","name":"4-5-6"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/#listItem","position":3,"name":"4-5-6","item":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/#listItem","name":"EN 534"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/#listItem","position":4,"name":"EN 534","previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/#listItem","name":"4-5-6"}}]},{"@type":"CollectionPage","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/#collectionpage","url":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/","name":"EN 534 - Techlab Systems","description":"PAPER AND BOARD \u2013 Thickness\/Bulk Density Determination-Individual Sheets","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/techlabsystems.com\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/techlabsystems.com\/eng\/#organization","name":"Techlab Systems","description":"Equipment for quality control tests","url":"https:\/\/techlabsystems.com\/eng\/","telephone":"+34943470007","logo":{"@type":"ImageObject","url":"https:\/\/techlabsystems.com\/eng\/wp-content\/uploads\/sites\/2\/2021\/04\/Techlabsystems-identidad-en.svg","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/#organizationLogo","width":677,"height":133},"image":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/techlabsystems.com\/eng\/#website","url":"https:\/\/techlabsystems.com\/eng\/","name":"Techlab Systems","description":"Equipment for quality control tests","inLanguage":"en-US","publisher":{"@id":"https:\/\/techlabsystems.com\/eng\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/products\/\" title=\"Products\">Products<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/\" title=\"4-5-6\">4-5-6<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEN 534\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/techlabsystems.com\/eng"},{"label":"Products","link":"https:\/\/techlabsystems.com\/eng\/products\/"},{"label":"4-5-6","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/"},{"label":"EN 534","link":"https:\/\/techlabsystems.com\/eng\/norma-en\/4-5-6\/en-534\/"}],"_links":{"self":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en"}],"about":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/taxonomies\/en"}],"up":[{"embeddable":true,"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/en\/1263"}],"wp:post_type":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/product?en=1290"},{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/normas?en=1290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}