{"id":1944,"count":0,"description":"CORRUGATED PAPERBOARD \u2013 Thickness Determination.","link":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/","name":"UNE 3034","slug":"une-3034","taxonomy":"une","parent":1707,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"CORRUGATED PAPERBOARD \u2013 Thickness Determination.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/#listItem\",\"name\":\"1-2-3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/#listItem\",\"position\":3,\"name\":\"1-2-3\",\"item\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/une-3034\\\/#listItem\",\"name\":\"UNE 3034\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/une-3034\\\/#listItem\",\"position\":4,\"name\":\"UNE 3034\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/une\\\/1-2-3\\\/#listItem\",\"name\":\"1-2-3\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/#collectionpage\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/\",\"name\":\"UNE 3034 - Techlab Systems\",\"description\":\"CORRUGATED PAPERBOARD \\u2013 Thickness Determination.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"telephone\":\"+34943470007\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/Techlabsystems-identidad-en.svg\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/#organizationLogo\",\"width\":677,\"height\":133},\"image\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/une\\\/1944\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/\",\"name\":\"Techlab Systems\",\"description\":\"Equipment for quality control tests\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/techlabsystems.com\\\/eng\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"UNE 3034 - Techlab Systems","description":"CORRUGATED PAPERBOARD \u2013 Thickness Determination.","canonical_url":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","position":1,"name":"Home","item":"https:\/\/techlabsystems.com\/eng","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/techlabsystems.com\/eng\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/#listItem","name":"1-2-3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/#listItem","position":3,"name":"1-2-3","item":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/","nextItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/#listItem","name":"UNE 3034"},"previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/#listItem","position":4,"name":"UNE 3034","previousItem":{"@type":"ListItem","@id":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/#listItem","name":"1-2-3"}}]},{"@type":"CollectionPage","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/#collectionpage","url":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/","name":"UNE 3034 - Techlab Systems","description":"CORRUGATED PAPERBOARD \u2013 Thickness Determination.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/techlabsystems.com\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/techlabsystems.com\/eng\/#organization","name":"Techlab Systems","description":"Equipment for quality control tests","url":"https:\/\/techlabsystems.com\/eng\/","telephone":"+34943470007","logo":{"@type":"ImageObject","url":"https:\/\/techlabsystems.com\/eng\/wp-content\/uploads\/sites\/2\/2021\/04\/Techlabsystems-identidad-en.svg","@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/#organizationLogo","width":677,"height":133},"image":{"@id":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/techlabsystems.com\/eng\/#website","url":"https:\/\/techlabsystems.com\/eng\/","name":"Techlab Systems","description":"Equipment for quality control tests","inLanguage":"en-US","publisher":{"@id":"https:\/\/techlabsystems.com\/eng\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/products\/\" title=\"Products\">Products<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/\" title=\"1-2-3\">1-2-3<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUNE 3034\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/techlabsystems.com\/eng"},{"label":"Products","link":"https:\/\/techlabsystems.com\/eng\/products\/"},{"label":"1-2-3","link":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/"},{"label":"UNE 3034","link":"https:\/\/techlabsystems.com\/eng\/une\/1-2-3\/une-3034\/"}],"_links":{"self":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une"}],"about":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/taxonomies\/une"}],"up":[{"embeddable":true,"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/une\/1707"}],"wp:post_type":[{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/product?une=1944"},{"href":"https:\/\/techlabsystems.com\/eng\/wp-json\/wp\/v2\/normas?une=1944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}